{"id":33511,"date":"2021-10-13T23:00:08","date_gmt":"2021-10-14T03:00:08","guid":{"rendered":"https:\/\/pontscouverts.com\/blogue\/?p=33511"},"modified":"2021-10-13T08:35:32","modified_gmt":"2021-10-13T12:35:32","slug":"melanie-visite-les-ponts-lambert-et-caron","status":"publish","type":"post","link":"https:\/\/pontscouverts.com\/blogue\/2021\/10\/13\/melanie-visite-les-ponts-lambert-et-caron\/","title":{"rendered":"M\u00e9lanie visite les ponts Lambert et Caron"},"content":{"rendered":"<div id=\"attachment_33512\" style=\"width: 2058px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/244999969_1915553128616611_7217347081697015984_n.jpg\"><img aria-describedby=\"caption-attachment-33512\" loading=\"lazy\" class=\"wp-image-33512 size-full\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/244999969_1915553128616611_7217347081697015984_n.jpg\" alt=\"\" width=\"2048\" height=\"1536\" srcset=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/244999969_1915553128616611_7217347081697015984_n.jpg 2048w, https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/244999969_1915553128616611_7217347081697015984_n-e1634128681414-150x113.jpg 150w, https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/244999969_1915553128616611_7217347081697015984_n-300x225.jpg 300w, https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/244999969_1915553128616611_7217347081697015984_n-768x576.jpg 768w, https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/244999969_1915553128616611_7217347081697015984_n-1024x768.jpg 1024w, https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/244999969_1915553128616611_7217347081697015984_n-624x468.jpg 624w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/a><p id=\"caption-attachment-33512\" class=\"wp-caption-text\">M\u00e9lanie Jobin Octobre 2021<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Notre collaboratrice M\u00e9lanie et sa famille ont profit\u00e9 de la belle fin de semaine de l&rsquo;Action de gr\u00e2ce pour visiter deux ponts couverts. Les couleurs d&rsquo;automne \u00e9taient au rendez-vous. Au <a href=\"https:\/\/pontscouverts.com\/blogue\/pont-lambert\/\"><span style=\"color: #0000ff;\">pont Lambert<\/span><\/a>, toujours aucune trace de travaux sur le lambris, le tablier ou la couverture. La phase 1 a \u00e9t\u00e9 r\u00e9alis\u00e9e en 2020 et on s&rsquo;attendait \u00e0 ce que la phase 2 se mette en branle cette ann\u00e9e. Au <a href=\"https:\/\/pontscouverts.com\/blogue\/pont-caron\/\"><span style=\"color: #0000ff;\">pont Caron<\/span><\/a>, tout est au beau fixe. Un gros merci \u00e0 M\u00e9lanie pour les magnifiques photos du jour.<\/span><\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-33511 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245325325_3236762069983005_1893453998731219987_n.jpg'><img width=\"113\" height=\"150\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245325325_3236762069983005_1893453998731219987_n-e1634041336263-113x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33519\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33519'>\n\t\t\t\tM\u00e9lanie Jobin Octobre 2021\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245292740_164107505920550_687949903166100099_n.jpg'><img width=\"113\" height=\"150\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245292740_164107505920550_687949903166100099_n-e1634041347277-113x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33517\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33517'>\n\t\t\t\tM\u00e9lanie Jobin Octobre 2021\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245332569_617772302557822_5503682199493255926_n.jpg'><img width=\"113\" height=\"150\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245332569_617772302557822_5503682199493255926_n-e1634041356867-113x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33520\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33520'>\n\t\t\t\tM\u00e9lanie Jobin Octobre 2021\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245466189_467582424706576_4863729569054090021_n.jpg'><img width=\"113\" height=\"150\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245466189_467582424706576_4863729569054090021_n-e1634041387383-113x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33524\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33524'>\n\t\t\t\tM\u00e9lanie Jobin Octobre 2021\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245201347_208093764757106_1711429130558837857_n.jpg'><img width=\"113\" height=\"150\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245201347_208093764757106_1711429130558837857_n-e1634041406494-113x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33516\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33516'>\n\t\t\t\tM\u00e9lanie Jobin Octobre 2021\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245056546_394347319029293_408727214187651470_n.jpg'><img width=\"113\" height=\"150\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245056546_394347319029293_408727214187651470_n-e1634041377666-113x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33513\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33513'>\n\t\t\t\tM\u00e9lanie Jobin Octobre 2021\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245456964_406714951061675_2325511104150999513_n.jpg'><img width=\"150\" height=\"113\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245456964_406714951061675_2325511104150999513_n-e1634041366447-150x113.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33523\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33523'>\n\t\t\t\tM\u00e9lanie Jobin Octobre 2021\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245315431_223399106382506_2869994064827956908_n.jpg'><img width=\"150\" height=\"113\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245315431_223399106382506_2869994064827956908_n-e1634041397949-150x113.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33518\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33518'>\n\t\t\t\tM\u00e9lanie Jobin Octobre 2021\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245442072_198865772319215_1633280466864510378_n.jpg'><img width=\"150\" height=\"113\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245442072_198865772319215_1633280466864510378_n-e1634041435347-150x113.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33521\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33521'>\n\t\t\t\tM\u00e9lanie Jobin Octobre 2021\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245443088_1311857505901594_5132178368934713937_n.jpg'><img width=\"150\" height=\"113\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245443088_1311857505901594_5132178368934713937_n-e1634041444116-150x113.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33522\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33522'>\n\t\t\t\tM\u00e9lanie Jobin Octobre 2021\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245157435_1042509289830321_2486808492141469080_n.jpg'><img width=\"113\" height=\"150\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245157435_1042509289830321_2486808492141469080_n-e1634041416646-113x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33514\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33514'>\n\t\t\t\tM\u00e9lanie Jobin Octobre 2021\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245183326_1019997975240495_7384302138610230213_n.jpg'><img width=\"113\" height=\"150\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/245183326_1019997975240495_7384302138610230213_n-e1634041426787-113x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33515\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33515'>\n\t\t\t\tM\u00e9lanie Jobin Octobre 2021\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Notre collaboratrice M\u00e9lanie et sa famille ont profit\u00e9 de la belle fin de semaine de l&rsquo;Action de gr\u00e2ce pour visiter deux ponts couverts. Les couleurs d&rsquo;automne \u00e9taient au rendez-vous. Au pont Lambert, toujours aucune trace de travaux sur le lambris, le tablier ou la couverture. La phase 1 a \u00e9t\u00e9 r\u00e9alis\u00e9e en 2020 et on [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/posts\/33511"}],"collection":[{"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/comments?post=33511"}],"version-history":[{"count":3,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/posts\/33511\/revisions"}],"predecessor-version":[{"id":33527,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/posts\/33511\/revisions\/33527"}],"wp:attachment":[{"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/media?parent=33511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/categories?post=33511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/tags?post=33511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}