{"id":33501,"date":"2021-10-12T23:00:08","date_gmt":"2021-10-13T03:00:08","guid":{"rendered":"https:\/\/pontscouverts.com\/blogue\/?p=33501"},"modified":"2021-10-12T08:12:50","modified_gmt":"2021-10-12T12:12:50","slug":"lautomne-au-pont-de-la-frontiere","status":"publish","type":"post","link":"https:\/\/pontscouverts.com\/blogue\/2021\/10\/12\/lautomne-au-pont-de-la-frontiere\/","title":{"rendered":"L&rsquo;automne au pont de la Fronti\u00e8re"},"content":{"rendered":"<div id=\"attachment_33502\" style=\"width: 1746px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N2.jpg\"><img aria-describedby=\"caption-attachment-33502\" loading=\"lazy\" class=\"wp-image-33502 size-full\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N2.jpg\" alt=\"\" width=\"1736\" height=\"1301\" srcset=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N2.jpg 1736w, https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N2-e1634040830439-150x113.jpg 150w, https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N2-300x225.jpg 300w, https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N2-768x576.jpg 768w, https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N2-1024x767.jpg 1024w, https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N2-624x468.jpg 624w\" sizes=\"(max-width: 1736px) 100vw, 1736px\" \/><\/a><p id=\"caption-attachment-33502\" class=\"wp-caption-text\">G\u00e9rald Arbour Octobre 2021<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Le <a href=\"https:\/\/pontscouverts.com\/blogue\/pont-de-la-frontiere\/\"><span style=\"color: #0000ff;\">pont de la Fronti\u00e8re<\/span><\/a> demeure bien populaire aupr\u00e8s des visiteurs comme a pu le constater G\u00e9rald lors d&rsquo;une sortie sur place le week-end dernier. Plusieurs touristes s&rsquo;y arr\u00eatent, y compris des cyclistes. Le pont couvert, dont l&rsquo;acc\u00e8s est toujours barricad\u00e9 pour des raisons de s\u00e9curit\u00e9, n&rsquo;est toujours pas facile \u00e0 photographier, peu importe l&rsquo;angle choisi. Rappelons que les cul\u00e9es sont \u00e0 refaire, mais que les fonds manquent. La grange ronde de Mansonville a offert \u00e0 nouveau pendant tout l&rsquo;\u00e9t\u00e9 l&rsquo;exposition de photos sur les ponts couverts de l&rsquo;Estrie. Merci \u00e0 G\u00e9rald pour les photos du jour.<\/span><\/p>\n\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-33501 gallery-columns-3 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N11.jpg'><img width=\"150\" height=\"113\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N11-e1634039721262-150x113.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33505\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33505'>\n\t\t\t\tG\u00e9rald Arbour Octobre 2021\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N6.jpg'><img width=\"150\" height=\"112\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N6-e1634039732312-150x112.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33503\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33503'>\n\t\t\t\tG\u00e9rald Arbour Octobre 2021\n\t\t\t\t<\/dd><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N9.jpg'><img width=\"112\" height=\"150\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N9-e1634039742638-112x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33504\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33504'>\n\t\t\t\tG\u00e9rald Arbour Octobre 2021\n\t\t\t\t<\/dd><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N12.jpg'><img width=\"112\" height=\"150\" src=\"https:\/\/pontscouverts.com\/blogue\/wp-content\/uploads\/2021\/10\/61-11-03-mansonville-2021-G\u00e9rald-Arbour-N12-e1634039753172-112x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" loading=\"lazy\" aria-describedby=\"gallery-1-33506\" \/><\/a>\n\t\t\t<\/dt>\n\t\t\t\t<dd class='wp-caption-text gallery-caption' id='gallery-1-33506'>\n\t\t\t\tG\u00e9rald Arbour Octobre 2021\n\t\t\t\t<\/dd><\/dl>\n\t\t\t<br style='clear: both' \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Le pont de la Fronti\u00e8re demeure bien populaire aupr\u00e8s des visiteurs comme a pu le constater G\u00e9rald lors d&rsquo;une sortie sur place le week-end dernier. Plusieurs touristes s&rsquo;y arr\u00eatent, y compris des cyclistes. Le pont couvert, dont l&rsquo;acc\u00e8s est toujours barricad\u00e9 pour des raisons de s\u00e9curit\u00e9, n&rsquo;est toujours pas facile \u00e0 photographier, peu importe l&rsquo;angle [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/posts\/33501"}],"collection":[{"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/comments?post=33501"}],"version-history":[{"count":3,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/posts\/33501\/revisions"}],"predecessor-version":[{"id":33509,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/posts\/33501\/revisions\/33509"}],"wp:attachment":[{"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/media?parent=33501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/categories?post=33501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/tags?post=33501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}