{"id":16351,"date":"2017-03-13T23:00:20","date_gmt":"2017-03-14T03:00:20","guid":{"rendered":"http:\/\/pontscouverts.com\/blogue\/?p=16351"},"modified":"2017-03-13T08:54:39","modified_gmt":"2017-03-13T12:54:39","slug":"les-ponts-couverts-de-ferme-rouge-vus-du-ciel","status":"publish","type":"post","link":"https:\/\/pontscouverts.com\/blogue\/2017\/03\/13\/les-ponts-couverts-de-ferme-rouge-vus-du-ciel\/","title":{"rendered":"Les ponts couverts de Ferme-Rouge vus du ciel"},"content":{"rendered":"<p><iframe loading=\"lazy\" width=\"625\" height=\"352\" src=\"https:\/\/www.youtube.com\/embed\/bizqI65SvLE?start=291&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Les images du jour ont \u00e9t\u00e9\u00a0film\u00e9es dans les Laurentides \u00e0 la fin du mois de f\u00e9vrier. Gr\u00e2ce \u00e0 un drone, on peut y voir les <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"http:\/\/www.pontscouverts.com\/Pontscouverts1\/Ferme-Rouge_Est.html\">ponts de Ferme-Rouge<\/a><\/span> sous un angle nouveau. Cela d\u00e9montre une fois de plus \u00e0 quel point le site est magnifique en toute saison. Je d\u00e9marre le vid\u00e9o \u00e0 4:50 minutes, soit l&rsquo;endroit o\u00f9 on peut voir les c\u00e9l\u00e8bres ponts jumel\u00e9s, mais pour ceux qui d\u00e9sirent reculer un peu, le clip d\u00e9bute avec de superbes images du barrage de Val-Barette. Je pense qu&rsquo;il s&rsquo;agit de l&rsquo;endroit o\u00f9 \u00e9tait situ\u00e9 le <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"http:\/\/www.pontscouverts.com\/Pontscouverts1\/Meilleur.html#grid\">pont Meilleur<\/a><\/span>.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les images du jour ont \u00e9t\u00e9\u00a0film\u00e9es dans les Laurentides \u00e0 la fin du mois de f\u00e9vrier. Gr\u00e2ce \u00e0 un drone, on peut y voir les ponts de Ferme-Rouge sous un angle nouveau. Cela d\u00e9montre une fois de plus \u00e0 quel point le site est magnifique en toute saison. Je d\u00e9marre le vid\u00e9o \u00e0 4:50 minutes, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/posts\/16351"}],"collection":[{"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/comments?post=16351"}],"version-history":[{"count":4,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/posts\/16351\/revisions"}],"predecessor-version":[{"id":16355,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/posts\/16351\/revisions\/16355"}],"wp:attachment":[{"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/media?parent=16351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/categories?post=16351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pontscouverts.com\/blogue\/wp-json\/wp\/v2\/tags?post=16351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}